{"id":9310,"date":"2024-07-22T10:29:11","date_gmt":"2024-07-22T07:29:11","guid":{"rendered":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/"},"modified":"2024-07-22T10:29:11","modified_gmt":"2024-07-22T07:29:11","slug":"waterproofing-a-floor-in-a-wooden-house","status":"publish","type":"post","link":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/","title":{"rendered":"Imperm\u00e9abilisation d&rsquo;un plancher dans une maison en bois"},"content":{"rendered":"\n<p>Pour qu&apos;une maison en bois reste confortable et structurellement saine, le sol doit \u00eatre imperm\u00e9abilis\u00e9. Les planchers en bois sont particuli\u00e8rement sensibles aux probl\u00e8mes li\u00e9s \u00e0 l&apos;humidit\u00e9, tels que la pourriture, la moisissure et le gauchissement. Vous pouvez prot\u00e9ger votre maison et augmenter la dur\u00e9e de vie de vos planchers en bois en veillant \u00e0 ce que l&apos;imperm\u00e9abilisation soit effectu\u00e9e correctement.<\/p>\n<p>Pour l&apos;imperm\u00e9abilisation des sols en bois, il existe de nombreux mat\u00e9riaux et m\u00e9thodes. Chaque choix pr\u00e9sente des avantages et est appropri\u00e9 dans certaines circonstances. Qu&apos;il s&apos;agisse de construire une nouvelle maison ou d&apos;en r\u00e9nover une ancienne, il est essentiel de choisir la strat\u00e9gie la mieux adapt\u00e9e \u00e0 vos besoins.<\/p>\n<p>Pour vous aider \u00e0 cr\u00e9er un plancher durable et r\u00e9sistant \u00e0 l&apos;humidit\u00e9, nous allons voir dans cet article l&apos;importance de l&apos;imperm\u00e9abilisation, les meilleurs mat\u00e9riaux \u00e0 utiliser et les instructions \u00e9tape par \u00e9tape. En utilisant les bonnes techniques, vous pouvez \u00e9viter les d\u00e9g\u00e2ts des eaux dans votre maison en bois et disposer d&apos;un espace de vie chaud et sec pendant de nombreuses ann\u00e9es.<\/p>\n<table>\n<tbody>\n<tr>\n<td>Aspect<\/td>\n<td>D\u00e9tails<\/td>\n<\/tr>\n<tr>\n<td>Pourquoi imperm\u00e9able \u00e0 l&apos;eau<\/td>\n<td>Pr\u00e9vient les d\u00e9g\u00e2ts caus\u00e9s par l&apos;humidit\u00e9, les moisissures et le pourrissement<\/td>\n<\/tr>\n<tr>\n<td>Mat\u00e9riaux n\u00e9cessaires<\/td>\n<td>Membrane imperm\u00e9able, produit d&apos;\u00e9tanch\u00e9it\u00e9, appr\u00eat, outils<\/td>\n<\/tr>\n<tr>\n<td>Pr\u00e9paration<\/td>\n<td>Nettoyer et s\u00e9cher le sol, appliquer l&apos;appr\u00eat<\/td>\n<\/tr>\n<tr>\n<td>Application<\/td>\n<td>Poser la membrane, sceller les bords, laisser s\u00e9cher<\/td>\n<\/tr>\n<tr>\n<td>\u00c9tapes finales<\/td>\n<td>V\u00e9rifier s&apos;il y a des lacunes, recouvrir d&apos;un rev\u00eatement de sol<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Pourquoi faut-il imperm\u00e9abiliser un plancher en bois ??<\/h2>\n<p>L&apos;humidit\u00e9 a deux effets sur la structure multicouche d&apos;un plancher en bois, qui se compose des planches, du sous-plancher et des solives :<\/p>\n<ul>\n<li>L&apos;imperm\u00e9abilisation d&apos;un plancher en bois peut se faire par des infiltrations d&apos;eau provenant du bas, de la cave ou du sol (maison priv\u00e9e), ou par des infiltrations dans le sol en b\u00e9ton des voisins inf\u00e9rieurs (rappelons que le b\u00e9ton laisse parfaitement passer les mol\u00e9cules de vapeur d&apos;eau) ;<\/li>\n<li>de l&apos;air int\u00e9rieur satur\u00e9 d&apos;eau &#8211; qui appara\u00eet en raison de l&apos;activit\u00e9 humaine (plantes d&apos;int\u00e9rieur, lavage, respiration des hommes et des animaux, cuisine, bain, etc.e).<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_1.jpg\"><\/p>\n<p>Le bois ne r\u00e9agit pas de mani\u00e8re significative \u00e0 une variation br\u00e8ve et insignifiante de l&apos;humidit\u00e9 ; il s\u00e9chera et reviendra \u00e0 son \u00e9tat d&apos;origine. En outre, si l&apos;humidit\u00e9 est importante ou si elle persiste pendant plusieurs jours ou semaines. Dans ce cas, les propri\u00e9taires doivent faire face \u00e0 plusieurs probl\u00e8mes qui se posent simultan\u00e9ment :<\/p>\n<ul>\n<li>Les planches, qui gonflent et s\u00e8chent, se d\u00e9forment &#8211; elles tournent ;<\/li>\n<li>l&apos;augmentation de la teneur en humidit\u00e9 du bois entra\u00eene la formation de condensation sur les lattes qui commencent \u00e0 pourrir ;<\/li>\n<li>Le bois humide est une excellente base pour la propagation des micro-organismes : champignons et moisissures.<\/li>\n<\/ul>\n<p>Il n&apos;y a qu&apos;une seule fa\u00e7on d&apos;\u00e9viter une trop grande humidification du bois : imperm\u00e9abiliser le dessus et le dessous des \u00e9l\u00e9ments de plancher en bois.<\/p>\n<h2>Nuances de l&apos;imperm\u00e9abilisation des sols en bois<\/h2>\n<p>Pour planifier l&apos;imperm\u00e9abilisation d&apos;un plancher en bois, il faut garder \u00e0 l&apos;esprit que les caract\u00e9ristiques doivent \u00eatre prises en compte en plus des nombreux avantages du bois.<\/p>\n<p>1. La capacit\u00e9 \u00e0 retenir l&apos;humidit\u00e9. Le bois absorbe l&apos;humidit\u00e9 de l&apos;air de mani\u00e8re assez active &#8211; on pourrait m\u00eame dire agressive. Tout cela est d\u00fb au fait que son humidit\u00e9 relative n&apos;est pas limit\u00e9e. Par cons\u00e9quent, les indicateurs d&apos;humidit\u00e9 relative des structures en bois de la maison changent en m\u00eame temps que la quantit\u00e9 d&apos;humidit\u00e9 dans l&apos;atmosph\u00e8re.<\/p>\n<p>Elles atteignent parfois une valeur critique qui d\u00e9clenche des processus destructeurs \u00e0 l&apos;int\u00e9rieur et \u00e0 l&apos;ext\u00e9rieur du bois : la pourriture s&apos;installe et des colonies de micro-organismes apparaissent sous forme de moisissures et de champignons.<\/p>\n<p>\u00c9tant donn\u00e9 qu&apos;une seule face expos\u00e9e du bois peut \u00eatre gravement satur\u00e9e d&apos;humidit\u00e9, l&apos;imperm\u00e9abilisation des structures en bois de tous les c\u00f4t\u00e9s est la seule d\u00e9fense contre de tels processus.<\/p>\n<p>2. Variation des dimensions lin\u00e9aires en cas d&apos;humidit\u00e9. Le bois gonfle donc lorsqu&apos;il absorbe de l&apos;humidit\u00e9, se dilatant de 0.1-0.3 % le long des fibres (sur la longueur), de 3 \u00e0 7 % dans le sens radial et de 6 \u00e0 10 % dans le sens tangentiel. Le processus inverse se produit lorsque le mat\u00e9riau s\u00e8che.<\/p>\n<p>De ce fait, les structures en bois sont constamment en mouvement. Cela pose des probl\u00e8mes pour les raisons suivantes : (1) il devient plus difficile de les r\u00e9parer ; (2) il devient plus difficile de choisir les mat\u00e9riaux d&apos;imperm\u00e9abilisation (dont certains fonctionnent parfaitement sur le b\u00e9ton mais seront d\u00e9chir\u00e9s par le bois) ; et (3) en raison des contraintes multidirectionnelles \u00e0 l&apos;int\u00e9rieur du bois caus\u00e9es par un s\u00e9chage in\u00e9gal, la surface du bois se fissure, cr\u00e9ant de grandes fentes. Il est \u00e9galement n\u00e9cessaire de prendre en compte cette \u00e9tape de la proc\u00e9dure d&apos;imperm\u00e9abilisation.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_2.jpg\"><\/p>\n<h2>Quelle est la meilleure fa\u00e7on d&apos;imperm\u00e9abiliser un plancher en bois ?<\/h2>\n<p>Il y a exactement quelques ann\u00e9es, les experts et les praticiens mentionnaient ce qui suit lorsqu&apos;ils discutaient des mat\u00e9riaux d&apos;\u00e9tanch\u00e9it\u00e9 :<\/p>\n<ul>\n<li>l&apos;isolation en rouleaux ;<\/li>\n<li>mastics ;<\/li>\n<li>appr\u00eats p\u00e9n\u00e9trants ;<\/li>\n<li>m\u00e9langes de pl\u00e2tre.<\/li>\n<\/ul>\n<p>Il \u00e9tait facile de naviguer dans cette liste, m\u00eame pour les clients non experts qui n&apos;avaient pas d&apos;exp\u00e9rience pr\u00e9alable dans les projets d&apos;imperm\u00e9abilisation.<\/p>\n<p>Tout est diff\u00e9rent aujourd&apos;hui. Compte tenu de la grande vari\u00e9t\u00e9 de mat\u00e9riaux d&apos;\u00e9tanch\u00e9it\u00e9 propos\u00e9s par les fabricants, m\u00eame les constructeurs exp\u00e9riment\u00e9s peuvent \u00e9prouver des difficult\u00e9s \u00e0 prendre la bonne d\u00e9cision. Les bricoleurs \u00e0 domicile peuvent s&apos;en servir :<\/p>\n<ul>\n<li>l&apos;imperm\u00e9abilisation par peinture ;<\/li>\n<li>le rev\u00eatement ;<\/li>\n<li>enduits ;<\/li>\n<li>rouleau ;<\/li>\n<li>mastic ;<\/li>\n<li>d&apos;impr\u00e9gnation ;<\/li>\n<li>couler ;<\/li>\n<li>remblayer ;<\/li>\n<li>pulv\u00e9ris\u00e9s ;<\/li>\n<li>p\u00e9n\u00e9trant.<\/li>\n<\/ul>\n<h3>Peinture d&apos;\u00e9tanch\u00e9it\u00e9<\/h3>\n<p>Les compositions liquides imperm\u00e9ables compos\u00e9es de bitume, de caoutchouc et de r\u00e9sines polym\u00e8res servent de repr\u00e9sentation de l&apos;imperm\u00e9abilisation des peintures. Appliqu\u00e9s en plusieurs couches pour cr\u00e9er une couche de protection imperm\u00e9able de 2 \u00e0 6 mm d&apos;\u00e9paisseur.<\/p>\n<h4>Types<\/h4>\n<p>Tant \u00e0 l&apos;int\u00e9rieur (pour les travaux int\u00e9rieurs) qu&apos;\u00e0 l&apos;ext\u00e9rieur (pour les travaux ext\u00e9rieurs), l&apos;isolation peinte peut \u00eatre utilis\u00e9e comme barri\u00e8re contre l&apos;humidit\u00e9. En plus de prot\u00e9ger le mat\u00e9riau mural de l&apos;humidit\u00e9, le traitement de fa\u00e7ade aide \u00e9galement \u00e0 pr\u00e9venir les premiers stades de d\u00e9gradation, tels que l&apos;\u00e9rosion, la fissuration et l&apos;effritement, qui sont des probl\u00e8mes courants avec le pl\u00e2tre d\u00e9coratif.<\/p>\n<h4>Compos\u00e9<\/h4>\n<p>Les compositions de peintures sont cr\u00e9\u00e9es \u00e0 l&apos;aide de :<\/p>\n<ul>\n<li>le brai bitumineux. En fonction de l&apos;utilisation, diff\u00e9rents additifs peuvent \u00eatre ajout\u00e9s \u00e0 la composition. Cette isolation fonctionne dans une plage de temp\u00e9rature allant de -30 o C \u00e0 +60 o C ;<\/li>\n<li>bitume et polym\u00e8res. L&apos;ajout de polym\u00e8res au bitume le rend \u00e9lastique et lui permet de r\u00e9sister \u00e0 des charges importantes lorsque la surface prot\u00e9g\u00e9e est d\u00e9form\u00e9e, par exemple un plancher en bois. Ils r\u00e9sistent aux basses temp\u00e9ratures et sont donc activement utilis\u00e9s pour l&apos;imperm\u00e9abilisation ext\u00e9rieure ;<\/li>\n<li>polym\u00e8res. Fabriqu\u00e9 \u00e0 partir de caoutchouc synth\u00e9tique et de r\u00e9sines polym\u00e8res. Ils sont performants dans les environnements agressifs ;<\/li>\n<li>polym\u00e8res et ciments. Utilis\u00e9s pour prot\u00e9ger les structures en b\u00e9ton de l&apos;humidit\u00e9.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_3.jpg\"><\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>L&apos;isolation par peinture pr\u00e9sente des avantages et des inconv\u00e9nients. Parmi les avantages, citons<\/p>\n<ul>\n<li>facilit\u00e9 d&apos;application. Presque toujours r\u00e9alis\u00e9e de ses propres mains ;<\/li>\n<li>accessibilit\u00e9 &#8211; en vente dans tous les points de vente de mat\u00e9riaux de construction ;<\/li>\n<li>Le bois ne r\u00e9agit pas de mani\u00e8re significative \u00e0 une variation br\u00e8ve et insignifiante de l&apos;humidit\u00e9 ;<\/li>\n<li>application rapide au rouleau ou au pistolet.<\/li>\n<\/ul>\n<p>Il y a deux inconv\u00e9nients. L&apos;une d&apos;entre elles &#8211; une dur\u00e9e de vie br\u00e8ve d&apos;environ six ans seulement &#8211; est importante. Le second est que les dommages m\u00e9caniques subis par la couche de surface sont facilement support\u00e9s.<\/p>\n<h4>L&apos;application<\/h4>\n<p>Apr\u00e8s avoir d\u00e9barrass\u00e9 la surface des d\u00e9bris (poussi\u00e8re, peinture et taches de graisse), on applique l&apos;imperm\u00e9abilisation \u00e0 la peinture. Pour \u00eatre absolument certain qu&apos;il ne reste pas de taches de graisse sous la couche d&apos;isolation, celle-ci est appr\u00eat\u00e9e, puis trait\u00e9e au white spirit ou \u00e0 l&apos;essence. Le treillis en fibre de verre est utilis\u00e9 pour renforcer les surfaces verticales et inclin\u00e9es afin d&apos;emp\u00eacher la couche d&apos;isolation de glisser.<\/p>\n<h3>Rev\u00eatement d&apos;\u00e9tanch\u00e9it\u00e9<\/h3>\n<p>Le rev\u00eatement est apparu comme une forme distincte d&apos;imperm\u00e9abilisation dans l&apos;Antiquit\u00e9, lorsque les gens ont commenc\u00e9 \u00e0 utiliser de l&apos;argile liquide comme barri\u00e8re r\u00e9sistante \u00e0 l&apos;eau. Les compos\u00e9s \u00e0 base de bitume ont commenc\u00e9 \u00e0 appara\u00eetre au fil du temps.<\/p>\n<p>Les rev\u00eatements d&apos;\u00e9tanch\u00e9it\u00e9 sont souvent class\u00e9s dans la cat\u00e9gorie des mastics dans la pratique, ce qui est souvent appropri\u00e9. Apr\u00e8s tout, certains mat\u00e9riaux d&apos;imperm\u00e9abilisation r\u00e9pondent parfaitement aux exigences des deux cat\u00e9gories d&apos;isolants. Cependant, il existe encore quelques diff\u00e9rences, bien que l\u00e9g\u00e8res, qui permettent de distinguer l&apos;isolation par enduit comme un type \u00e0 part enti\u00e8re.<\/p>\n<h4>Compos\u00e9<\/h4>\n<p>Les \u00e9l\u00e9ments suivants sont utilis\u00e9s dans le processus de production du rev\u00eatement d&apos;imperm\u00e9abilisation :<\/p>\n<ul>\n<li>bitume, additionn\u00e9 de ciment, de cendres, de craie, de dolomie et d&apos;autres min\u00e9raux ;<\/li>\n<li>le bitume avec l&apos;ajout de miettes de caoutchouc ;<\/li>\n<li>le bitume avec des polym\u00e8res auxquels ont \u00e9t\u00e9 ajout\u00e9s des min\u00e9raux du premier \u00e9l\u00e9ment de la liste ;<\/li>\n<li>bitume avec appr\u00eat.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_4.jpg\"><\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>L&apos;enduction de l&apos;isolation pr\u00e9sente plusieurs avantages, notamment<\/p>\n<ul>\n<li>la couche appliqu\u00e9e est absolument \u00e9tanche ;<\/li>\n<li>bonnes propri\u00e9t\u00e9s de protection contre le bruit et la chaleur ;<\/li>\n<li>facilit\u00e9 d&apos;application ;<\/li>\n<li>une grande \u00e9lasticit\u00e9, ce qui permet de r\u00e9parer rapidement les dommages subis par la surface.<\/li>\n<\/ul>\n<p>Parmi les inconv\u00e9nients, citons :<\/p>\n<ul>\n<li>la n\u00e9cessit\u00e9 d&apos;appliquer plusieurs couches (minimum 2) ;<\/li>\n<li>un processus d&apos;isolation qui prend du temps : chaque couche suivante est appliqu\u00e9e sur la couche pr\u00e9c\u00e9dente compl\u00e8tement s\u00e8che ;<\/li>\n<li>haute toxicit\u00e9 de l&apos;enduit appliqu\u00e9 \u00e0 chaud ;<\/li>\n<li>interdiction d&apos;utiliser des mat\u00e9riaux chauffants dans les pi\u00e8ces \u00e0 structure en bois &#8211; risque \u00e9lev\u00e9 d&apos;incendie.<\/li>\n<\/ul>\n<h4>Application<\/h4>\n<p>A l&apos;aide d&apos;une spatule \u00e9troite, d&apos;un rouleau ou d&apos;une brosse dure, le rev\u00eatement d&apos;\u00e9tanch\u00e9it\u00e9 est appliqu\u00e9 sur une surface qui a \u00e9t\u00e9 d\u00e9barrass\u00e9e des d\u00e9bris, de la poussi\u00e8re et de la graisse. Il est recouvert d&apos;un appr\u00eat bitumineux pour am\u00e9liorer l&apos;adh\u00e9rence \u00e0 la surface. Le white-spirit est utilis\u00e9 pour diluer un enduit tr\u00e8s \u00e9pais. Appliquer plusieurs couches de peinture jusqu&apos;\u00e0 l&apos;obtention d&apos;un noir profond.<\/p>\n<h3>Imperm\u00e9abilisation au pl\u00e2tre<\/h3>\n<p>M\u00e9lange complexe de ciment et d&apos;additifs, le pl\u00e2tre isolant cr\u00e9e un film \u00e9lastique et r\u00e9sistant \u00e0 l&apos;eau lorsqu&apos;il est appliqu\u00e9. propos\u00e9 sous forme de m\u00e9lange sec.<\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>Les mat\u00e9riaux d&apos;\u00e9tanch\u00e9it\u00e9 \u00e0 base de ciment offrent de nombreux avantages. Les mat\u00e9riaux d&apos;\u00e9tanch\u00e9it\u00e9 \u00e0 base de ciment pr\u00e9sentent de nombreux avantages et inconv\u00e9nients :<\/p>\n<ul>\n<li>durabilit\u00e9 &#8211; la dur\u00e9e de vie est d&apos;environ 30 ans ;<\/li>\n<li>r\u00e9sistance \u00e9lev\u00e9e aux contraintes m\u00e9caniques ;<\/li>\n<li>facilit\u00e9 d&apos;application &#8211; un bricoleur sans exp\u00e9rience professionnelle peut diluer la solution et l&apos;appliquer sur la surface isol\u00e9e ;<\/li>\n<li>il n&apos;est pas n\u00e9cessaire de r\u00e9parer et de niveler la surface isol\u00e9e : l&apos;isolateur couvrira non seulement la courbure, les fissures et les \u00e9clats, mais servira \u00e9galement de solution de r\u00e9paration ;<\/li>\n<li>excellente r\u00e9sistance \u00e0 l&apos;eau ;<\/li>\n<li>la possibilit\u00e9 d&apos;utiliser comme adh\u00e9sif pour l&apos;isolation.<\/li>\n<\/ul>\n<p>De plus, l&apos;application de pratiquement n&apos;importe quel type de finition directement sur l&apos;isolation est un \u00e9norme avantage.<\/p>\n<p>Voici quelques-uns des d\u00e9fauts de ce mat\u00e9riau :<\/p>\n<ul>\n<li>crainte des vibrations et du r\u00e9tr\u00e9cissement du b\u00e2timent &#8211; fissures ;<\/li>\n<li>en cas de changements brusques de temp\u00e9rature, commence \u00e0 s&apos;effondrer.<\/li>\n<\/ul>\n<h4>M\u00e9thode d&apos;application<\/h4>\n<p>Afin d&apos;utiliser le mortier de pl\u00e2tre pour imperm\u00e9abiliser la surface, les op\u00e9rations technologiques suivantes doivent \u00eatre effectu\u00e9es dans l&apos;ordre :<\/p>\n<ul>\n<li>la surface trait\u00e9e est nettoy\u00e9e de la salet\u00e9 et de la poussi\u00e8re, les petites fissures se dilatent ;<\/li>\n<li>l&apos;appr\u00eat est appliqu\u00e9. Vous pouvez utiliser de la colle PVA dilu\u00e9e ;<\/li>\n<li>apr\u00e8s s\u00e9chage de l&apos;appr\u00eat, la solution est m\u00e9lang\u00e9e pour former une p\u00e2te \u00e9paisse ;<\/li>\n<li>La solution est appliqu\u00e9e \u00e0 l&apos;aide d&apos;une spatule sur la surface isol\u00e9e ;<\/li>\n<li>apr\u00e8s le s\u00e9chage de la premi\u00e8re couche, appliquer la seconde, en utilisant des mouvements perpendiculaires \u00e0 la premi\u00e8re couche.<\/li>\n<\/ul>\n<h3>Rouleau d&apos;\u00e9tanch\u00e9it\u00e9<\/h3>\n<p>Sauf exception (feuille d&apos;aluminium), l&apos;imperm\u00e9abilisation en rouleaux est constitu\u00e9e de deux couches de mat\u00e9riau. Une couche est la base d&apos;une seconde couche \u00e9tanche de goudron, de caoutchouc butyle ou de bitume. La fondation pourrait \u00eatre :<\/p>\n<ul>\n<li>la fibre de verre ;<\/li>\n<li>la fibre de verre ;<\/li>\n<li>mat\u00e9riaux en polyester ;<\/li>\n<li>le carton (repr\u00e9sent\u00e9 par le feutre de toiture) ;<\/li>\n<li>papier d&apos;amiante (papier goudronn\u00e9).<\/li>\n<\/ul>\n<h4>Vari\u00e9t\u00e9s selon la m\u00e9thode d&apos;application<\/h4>\n<p>L&apos;isolation en rouleau peut \u00eatre (et est parfois) incluse dans la liste des types ind\u00e9pendants.<\/p>\n<ul>\n<li>adh\u00e9sif &#8211; fix\u00e9 \u00e0 la surface isol\u00e9e et les uns aux autres lors de l&apos;application multicouche \u00e0 l&apos;aide de bitume ;<\/li>\n<li>Il s&apos;agit d&apos;un produit qui se situe entre l&apos;huile de machine et le carburant diesel ; &#8211; construit &#8211; lors de la fabrication, une face est impr\u00e9gn\u00e9e d&apos;un liant, qui est chauff\u00e9 \u00e0 l&apos;aide d&apos;un br\u00fbleur \u00e0 gaz lors de la pose ;<\/li>\n<li>polym\u00e8re &#8211; les bords du rouleau sont trait\u00e9s avec des compos\u00e9s polym\u00e8res qui, chauff\u00e9s avec un s\u00e8che-cheveux de chantier, sont herm\u00e9tiquement coll\u00e9s \u00e0 la toile d\u00e9j\u00e0 pos\u00e9e.<\/li>\n<\/ul>\n<p>Le projet &quot;Imperm\u00e9abilisation du sol avant la pose de la chape&quot; des techniques d&apos;installation illustr\u00e9es.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_5.jpg\"><\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>L&apos;isolation en rouleau pr\u00e9sente quelques avantages. Parmi les avantages, citons<\/p>\n<ul>\n<li>le processus d&apos;installation est simple, m\u00eame si certains types n\u00e9cessitent l&apos;utilisation d&apos;appareils de chauffage ;<\/li>\n<li>prix peu \u00e9lev\u00e9.<\/li>\n<\/ul>\n<p>Et c&apos;est pratiquement tout. Parmi les inconv\u00e9nients, on peut citer<\/p>\n<ul>\n<li>la pr\u00e9sence de joints de raccordement, qui n\u00e9cessite la pose d&apos;une deuxi\u00e8me couche ;<\/li>\n<li>poids important, cr\u00e9ant une charge suppl\u00e9mentaire sur les structures de soutien ;<\/li>\n<li>impossibilit\u00e9 d&apos;isoler des surfaces \u00e0 g\u00e9om\u00e9trie complexe ;<\/li>\n<li>perte d&apos;\u00e9tanch\u00e9it\u00e9 dans des conditions de vibration, et n&apos;est donc pas recommand\u00e9 pour une utilisation pr\u00e8s des chantiers de construction et des autoroutes.<\/li>\n<\/ul>\n<h3>Imperm\u00e9abilisation au mastic<\/h3>\n<p>une masse plastique tr\u00e8s visqueuse, connue sous le nom de mastic d&apos;\u00e9tanch\u00e9it\u00e9, est cr\u00e9\u00e9e en combinant des additifs adh\u00e9sifs, des charges finement broy\u00e9es et des mati\u00e8res organiques aux qualit\u00e9s astringentes.<\/p>\n<h4>Types<\/h4>\n<p>Une fa\u00e7on d&apos;imperm\u00e9abiliser les mastics est de :<\/p>\n<ul>\n<li>bitume &#8211; compos\u00e9 de plusieurs types de bitume sans additifs. Vous pouvez le faire vous-m\u00eame ;<\/li>\n<li>le bitume-polym\u00e8re (la plupart des types d&apos;\u00e9tanch\u00e9it\u00e9 de ce type peuvent \u00e9galement \u00eatre consid\u00e9r\u00e9s comme des rev\u00eatements) ;<\/li>\n<li>ciment-polym\u00e8re ;<\/li>\n<li>polym\u00e8re.<\/li>\n<\/ul>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>Parmi les avantages des mastics, on peut citer<\/p>\n<ul>\n<li>maintien de l&apos;\u00e9lasticit\u00e9 \u00e0 basse temp\u00e9rature ;<\/li>\n<li>une expansion lin\u00e9aire suffisante, sans perte de propri\u00e9t\u00e9s protectrices, avec des d\u00e9formations constantes de la base trait\u00e9e ;<\/li>\n<li>la bonne adh\u00e9rence aux principaux types de mat\u00e9riaux de construction ;<\/li>\n<li>capacit\u00e9 \u00e0 s&apos;\u00e9taler en couche mince ;<\/li>\n<li>polyvalence &#8211; peut \u00eatre utilis\u00e9 comme adh\u00e9sif (pour les mat\u00e9riaux lamin\u00e9s) et comme appr\u00eat pour l&apos;imperm\u00e9abilisation des peintures ;<\/li>\n<li>disponibilit\u00e9 de mat\u00e9riaux pr\u00eats \u00e0 l&apos;emploi.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_6.jpg\"><\/p>\n<ul>\n<li>co\u00fbt assez \u00e9lev\u00e9 de la plupart des types ;<\/li>\n<li>la difficult\u00e9 de choisir en raison de l&apos;\u00e9norme assortiment et des diff\u00e9rentes sp\u00e9cialisations, ce qui est vraiment un probl\u00e8me pour un constructeur non professionnel ;<\/li>\n<li>contient une quantit\u00e9 importante de composants toxiques et inflammables, ce qui n\u00e9cessite l&apos;utilisation d&apos;\u00e9quipements de protection et une manipulation prudente du feu ;<\/li>\n<li>faible r\u00e9sistance m\u00e9canique &#8211; n\u00e9cessite un renforcement avec de la fibre de verre ou un treillis en fibre de verre ;<\/li>\n<li>la grande majorit\u00e9 des mastics ne sont pas compatibles avec la colle \u00e0 carrelage, qui doit \u00eatre pos\u00e9e sur la chape de ciment imperm\u00e9able.<\/li>\n<\/ul>\n<h4>Application<\/h4>\n<p>La technologie utilis\u00e9e pour appliquer la peinture isolante est exactement la m\u00eame que celle utilis\u00e9e pour prot\u00e9ger diff\u00e9rentes surfaces de l&apos;humidit\u00e9 \u00e0 l&apos;aide de mastic.<\/p>\n<h3>Imperm\u00e9abilisation par impr\u00e9gnation<\/h3>\n<p>Les principaux ingr\u00e9dients de l&apos;isolation impr\u00e9gn\u00e9e sont le ciment, le sable et une vari\u00e9t\u00e9 de produits chimiques \u00e0 petites particules. Le ciment et la surface trait\u00e9e sont reli\u00e9s par ces particules. Lorsque les substances s&apos;infiltrent dans les pores du mat\u00e9riau de construction \u00e0 l&apos;\u00e9tat liquide, elles r\u00e9agissent chimiquement avec le ciment pour former un film durable et imperm\u00e9able \u00e0 la vapeur d&apos;eau.<\/p>\n<h4>Types<\/h4>\n<p>Dans la pratique, quelques mat\u00e9riaux totalement diff\u00e9rents sont utilis\u00e9s en plus de l&apos;impr\u00e9gnation au ciment. Nous pouvons attirer l&apos;attention sur :<\/p>\n<ul>\n<li>oligom\u00e8re &#8211; l&apos;un des types d&apos;imperm\u00e9abilisation les moins chers. Il s&apos;agit d&apos;un produit interm\u00e9diaire entre l&apos;huile de machine et le carburant diesel ;<\/li>\n<li>acrylique &#8211; se compose enti\u00e8rement d&apos;acrylates ;<\/li>\n<li>le silicone, qui, avec le ciment, peut contenir des silanes, des siliconates, des siloxanes et d&apos;autres polym\u00e8res de ce groupe.<\/li>\n<\/ul>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<ul>\n<li>facile \u00e0 appliquer ;<\/li>\n<li>aucune protection suppl\u00e9mentaire n&apos;est n\u00e9cessaire apr\u00e8s l&apos;application ;<\/li>\n<li>la surface \u00e0 traiter ne doit pas \u00eatre appr\u00eat\u00e9e ;<\/li>\n<li>augmente la r\u00e9sistance m\u00e9canique du b\u00e9ton et la r\u00e9sistance au gel ;<\/li>\n<li>pr\u00e9sente une grande inertie aux produits chimiques agressifs.<\/li>\n<\/ul>\n<p>Le seul et unique inconv\u00e9nient est la sp\u00e9cialisation limit\u00e9e. Les impr\u00e9gnations sont destin\u00e9es au b\u00e9ton qui vient d&apos;\u00eatre pos\u00e9.<\/p>\n<h4>Application<\/h4>\n<p>La composition d&apos;impr\u00e9gnation peut \u00eatre appliqu\u00e9e \u00e0 l&apos;aide d&apos;un pinceau ou d&apos;une brosse \u00e0 peinture, selon le type. Peu importe que la surface \u00e0 traiter soit humide ou s\u00e8che, il suffit qu&apos;elle soit propre.<\/p>\n<h3>Imperm\u00e9abilisation par coul\u00e9e<\/h3>\n<p>L&apos;\u00e9tanch\u00e9it\u00e9 coul\u00e9e est la meilleure m\u00e9thode de protection contre l&apos;humidit\u00e9. Elle est compl\u00e9t\u00e9e par l&apos;application d&apos;une solution imperm\u00e9able sur l&apos;ensemble de la surface.<\/p>\n<h4>Types<\/h4>\n<p>L&apos;\u00e9tanch\u00e9it\u00e9 coul\u00e9e est class\u00e9e comme chaude ou froide en fonction de l&apos;\u00e9tat de la surface apr\u00e8s le coulage.<\/p>\n<h4>Compos\u00e9<\/h4>\n<p>Avec l&apos;ajout de diff\u00e9rents types de polym\u00e8res, les compositions d&apos;asphalte et de b\u00e9ton bitumineux constituent la base de la pr\u00e9paration de l&apos;isolation par coul\u00e9e \u00e0 chaud. La plupart des gens connaissent l&apos;isolation coul\u00e9e \u00e0 froid, qui est \u00e9galement appel\u00e9e &quot;liquide&quot; caoutchouc et verre.<\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>La mani\u00e8re la plus concise de r\u00e9sumer tous les avantages de l&apos;imperm\u00e9abilisation par coul\u00e9e est de dire qu&apos;il s&apos;agit actuellement de la meilleure m\u00e9thode pour prot\u00e9ger diff\u00e9rents types de structures contre l&apos;humidit\u00e9. Un b\u00e9mol : cher. Un autre inconv\u00e9nient existait jusqu&apos;\u00e0 r\u00e9cemment : les murs verticaux ne pouvaient pas \u00eatre utilis\u00e9s avec ce produit. Le probl\u00e8me a \u00e9t\u00e9 r\u00e9solu en ajoutant des additifs uniques au m\u00e9lange.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_7.jpg\"><\/p>\n<h4>Application<\/h4>\n<p>Il est possible de sceller tous les interstices et fissures de la surface en versant ou en pulv\u00e9risant du &quot;liquide&quot; verre. De plus, l&apos;isolant chaud est vers\u00e9 sur la surface \u00e0 traiter, formant ainsi une couche uniforme et continue de mat\u00e9riau hydrofuge. Ils se tournent vers le nivellement si la fluidit\u00e9 est insuffisante.<\/p>\n<h3>Imperm\u00e9abilisation des remblais<\/h3>\n<p>L&apos;imperm\u00e9abilisation des remblais fait r\u00e9f\u00e9rence \u00e0 une s\u00e9rie de proc\u00e9dures qui maintiennent les \u00e9l\u00e9ments structurels du b\u00e2timent au sec, plut\u00f4t qu&apos;\u00e0 un type particulier d&apos;isolant. Les mat\u00e9riaux granulaires, fibreux, pulv\u00e9rulents ou granuleux sont utilis\u00e9s comme isolants de remblai :<\/p>\n<ul>\n<li>sable de perlite ;<\/li>\n<li>bentonite ;<\/li>\n<li>la laine de basalte ;<\/li>\n<li>laitier ;<\/li>\n<li>granul\u00e9s de mousse.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_8.jpg\"><\/p>\n<p>Les mat\u00e9riaux sont soit remplis d&apos;eau, soit recouverts d&apos;un mortier de ciment pour cr\u00e9er une couche imperm\u00e9able.<\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<ul>\n<li>faible co\u00fbt ;<\/li>\n<li>la simplicit\u00e9 de mise en \u0153uvre ;<\/li>\n<li>durabilit\u00e9.<\/li>\n<\/ul>\n<p>L&apos;\u00e9paisseur importante de la couche d&apos;imperm\u00e9abilisation et son retrait sous l&apos;effet des vibrations sont des inconv\u00e9nients dont les propri\u00e9taires de maisons situ\u00e9es \u00e0 proximit\u00e9 d&apos;autoroutes et de chantiers de construction doivent \u00eatre conscients.<\/p>\n<h3>Imperm\u00e9abilisation par pulv\u00e9risation<\/h3>\n<p>Gr\u00e2ce \u00e0 son passage extr\u00eamement rapide \u00e0 l&apos;\u00e9tat solide au contact de l&apos;air, l&apos;imperm\u00e9abilisation projet\u00e9e produit un rev\u00eatement sans joint incroyablement efficace sur n&apos;importe quelle surface, qu&apos;elle soit horizontale, verticale ou inclin\u00e9e.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_9.jpg\"><\/p>\n<p>M\u00e9langes modifi\u00e9s de &quot;liquides caoutchouc &quot;liquide le verre, et d&apos;autres imperm\u00e9abilisants liquides \u00e0 base de bitume, d&apos;acrylique et de polyur\u00e9thane sont utilis\u00e9s pour la pulv\u00e9risation. Il n&apos;est pas utilis\u00e9 dans les m\u00e9nages en raison de la complexit\u00e9 de l&apos;\u00e9quipement.<\/p>\n<h3>Imperm\u00e9abilisation par p\u00e9n\u00e9tration<\/h3>\n<p>L&apos;aspect fondamental de l&apos;imperm\u00e9abilisation p\u00e9n\u00e9trante est la modification de la structure mol\u00e9culaire du b\u00e9ton provoqu\u00e9e par les agents d&apos;impr\u00e9gnation. Des cristaux insolubles dans l&apos;eau sont produits par la composition liquide de la substance d&apos;impr\u00e9gnation qui r\u00e9agit chimiquement avec le ciment au fur et \u00e0 mesure qu&apos;elle p\u00e9n\u00e8tre en profondeur. Les scientifiques ont r\u00e9cemment r\u00e9ussi \u00e0 cr\u00e9er des isolateurs capables de p\u00e9n\u00e9trer le b\u00e9ton jusqu&apos;\u00e0 50 centim\u00e8tres de profondeur. Simultan\u00e9ment, la quantit\u00e9 des fonctions de ces impr\u00e9gnations a fortement augment\u00e9. Le b\u00e9ton devient plus solide et plus r\u00e9sistant aux produits chimiques agressifs, en plus d&apos;\u00eatre imperm\u00e9able \u00e0 l&apos;humidit\u00e9.<\/p>\n<p>Les impr\u00e9gnations sont disponibles \u00e0 l&apos;achat sous forme de liquides (appel\u00e9s &quot;Penetron&quot;) L&apos;impr\u00e9gnation se fait \u00e0 l&apos;aide d&apos;un pinceau ou d&apos;un rouleau, en plusieurs passes, sur une surface de b\u00e9ton d\u00e9j\u00e0 mouill\u00e9e (appel\u00e9e &quot;Kema&quot;).<\/p>\n<h4>Avantages et inconv\u00e9nients<\/h4>\n<p>Les avantages sont ind\u00e9niables :<\/p>\n<ul>\n<li>dur\u00e9e de vie illimit\u00e9e ;<\/li>\n<li>Les impr\u00e9gnations sont disponibles \u00e0 l&apos;achat sous forme de liquides (appel\u00e9s &quot;p\u00e9n\u00e9trons&quot;) ;<\/li>\n<li>la capacit\u00e9 de restaurer la surface du b\u00e9ton &#8211; le resserrement de toutes les microfissures.<\/li>\n<\/ul>\n<ul>\n<li>le mastic est uniquement destin\u00e9 au b\u00e9ton ;<\/li>\n<li>prix tr\u00e8s \u00e9lev\u00e9 ;<\/li>\n<li>long cycle technologique.<\/li>\n<\/ul>\n<h4>Application<\/h4>\n<p>A l&apos;aide d&apos;un pinceau ou d&apos;un rouleau, l&apos;impr\u00e9gnation est appliqu\u00e9e en plusieurs passes sur une surface en b\u00e9ton d\u00e9j\u00e0 mouill\u00e9e. Apr\u00e8s s\u00e9chage de la premi\u00e8re couche, chaque couche suivante est appliqu\u00e9e. Chaque passage doit \u00eatre effectu\u00e9 avec la surface mouill\u00e9e.<\/p>\n<p>En conclusion, une base et une sous-couche en b\u00e9ton sont possibles pour un plancher en bois. Tous les types de mat\u00e9riaux d&apos;imperm\u00e9abilisation mentionn\u00e9s ci-dessus peuvent \u00eatre utilis\u00e9s pour imperm\u00e9abiliser un sol en b\u00e9ton.<\/p>\n<p>Dans une maison priv\u00e9e, il existe plusieurs m\u00e9thodes pour imperm\u00e9abiliser les sols en bois, notamment la peinture, l&apos;enduit, le rouleau, le mastic et l&apos;isolation par impr\u00e9gnation.<\/p>\n<h2>Y a-t-il une d\u00e9pendance \u00e0 l&apos;\u00e9gard du rev\u00eatement de finition ??<\/h2>\n<p>Les mat\u00e9riaux d&apos;imperm\u00e9abilisation et la couche de finition d&apos;un sol en bois ne sont pas antagonistes. Une exception serait l&apos;utilisation d&apos;un mastic bitumineux pour imperm\u00e9abiliser un sol en bois sous un carrelage dans une salle de bain. Elles ne peuvent pas \u00eatre utilis\u00e9es avec la colle \u00e0 carrelage, qui n\u00e9cessite l&apos;installation d&apos;une feuille d&apos;OSB, d&apos;un contreplaqu\u00e9 ou d&apos;une plaque de pl\u00e2tre entre les deux.<\/p>\n<p>Seule l&apos;\u00e9tanch\u00e9it\u00e9 adh\u00e9sive (feu ouvert) et diff\u00e9rents types d&apos;isolants appliqu\u00e9s \u00e0 chaud (g\u00e9n\u00e9ralement chauff\u00e9s \u00e0 +300 o C), ce qui est essentiel pour le bois (l&apos;inflammation se produit \u00e0 +200 o C), sont limit\u00e9s pour des raisons de s\u00e9curit\u00e9.<\/p>\n<blockquote><p>\n   Il est essentiel d&apos;imperm\u00e9abiliser le plancher d&apos;une maison en bois pour \u00e9viter les d\u00e9g\u00e2ts dus \u00e0 l&apos;humidit\u00e9, la formation de moisissures et la d\u00e9t\u00e9rioration de la structure. Les probl\u00e8mes li\u00e9s \u00e0 l&apos;eau peuvent \u00eatre \u00e9vit\u00e9s et la dur\u00e9e de vie des planchers en bois peut \u00eatre augment\u00e9e par les propri\u00e9taires en utilisant des solutions d&apos;imperm\u00e9abilisation telles que des membranes, des produits d&apos;\u00e9tanch\u00e9it\u00e9 et une ventilation ad\u00e9quate. En emp\u00eachant l&apos;humidit\u00e9 de p\u00e9n\u00e9trer, ce proc\u00e9d\u00e9 permet non seulement de prot\u00e9ger le bois, mais aussi de garantir un environnement de vie plus sain.\n  <\/p><\/blockquote>\n<h2>Mat\u00e9riaux et outils n\u00e9cessaires<\/h2>\n<p>Pour imperm\u00e9abiliser et cr\u00e9er un pare-vapeur sur un plancher en bois, les fournitures et \u00e9quipements suivants sont n\u00e9cessaires :<\/p>\n<ul>\n<li>mastic d&apos;\u00e9tanch\u00e9it\u00e9, impr\u00e9gnation, etc.d.;<\/li>\n<li>film pare-vapeur (membrane) ;<\/li>\n<li>les mastics pour colmater les fissures et les crevasses ;<\/li>\n<li>impr\u00e9gnation bio- et ignifuge ;<\/li>\n<li>appr\u00eat pour le bois (l&apos;option la plus efficace est un appr\u00eat \u00e9mulsion hydrosoluble \u00e0 base de bitume) ;<\/li>\n<li>la bande autocollante d&apos;\u00e9tanch\u00e9it\u00e9 ;<\/li>\n<li>caoutchouc brut (rev\u00eatements en caoutchouc) ;<\/li>\n<li>pinceau ;<\/li>\n<li>couteau de construction ;<\/li>\n<li>la roulette ;<\/li>\n<li>aspirateur ou balai.<\/li>\n<\/ul>\n<h2>Instructions pour l&apos;imperm\u00e9abilisation du sol<\/h2>\n<p>Plusieurs technologies peuvent \u00eatre utilis\u00e9es pour imperm\u00e9abiliser un plancher en bois :<\/p>\n<ul>\n<li>sur le sol (dans les maisons priv\u00e9es) ;<\/li>\n<li>plancher en bois brut (dans les maisons et les appartements).<\/li>\n<\/ul>\n<p>A son tour, en fonction des mat\u00e9riaux d&apos;\u00e9tanch\u00e9it\u00e9 choisis, il existe diff\u00e9rentes mani\u00e8res de prot\u00e9ger le sous-plancher de l&apos;humidit\u00e9.<\/p>\n<h3>Imperm\u00e9abilisation d&apos;un plancher en bois au sol<\/h3>\n<p>L&apos;imperm\u00e9abilisation d&apos;un plancher en bois au niveau du sol est une pratique courante dans la construction priv\u00e9e. Voici l&apos;algorithme \u00e9tape par \u00e9tape utilis\u00e9 pour mettre en \u0153uvre cette technologie :<\/p>\n<ul>\n<li>une fosse d&apos;environ 40 \u00e0 50 cm de profondeur est creus\u00e9e dans le sol sous la maison ;<\/li>\n<li>le fond de la fosse est soigneusement nivel\u00e9 puis compact\u00e9 manuellement ou \u00e0 l&apos;aide d&apos;une plaque vibrante ;<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_10.jpg\"><\/p>\n<ul>\n<li>une couche de sable de 10 cm d&apos;\u00e9paisseur est coul\u00e9e (en cas de nappe phr\u00e9atique \u00e9lev\u00e9e, le remblai de sable est r\u00e9alis\u00e9 jusqu&apos;\u00e0 20 cm), nivel\u00e9e, puis compact\u00e9e ;<\/li>\n<li>un remblai de gravier de carri\u00e8re grossier ou moyen ou d&apos;argile expans\u00e9e (si l&apos;on veut isoler en m\u00eame temps le fond du b\u00e2timent) d&apos;une \u00e9paisseur maximale de 20 cm est r\u00e9alis\u00e9 sur le sable ;<\/li>\n<li>Le gravier (argile expans\u00e9e) est nivel\u00e9 \u00e0 l&apos;aide d&apos;un r\u00e2teau ;<\/li>\n<li>une couche de sable de 10 cm d&apos;\u00e9paisseur est vers\u00e9e sur le dessus, nivel\u00e9e, compact\u00e9e \u00e0 l&apos;aide d&apos;une plaque vibrante ou manuellement ;<\/li>\n<li>le sable est vers\u00e9 avec de l&apos;eau et \u00e0 nouveau compact\u00e9 (en cas d&apos;utilisation d&apos;argile expans\u00e9e, seule la couche sup\u00e9rieure de sable est humidifi\u00e9e avec de l&apos;eau) ;<\/li>\n<li>le sable est s\u00e9ch\u00e9 naturellement. Par temps humide, il est recouvert d&apos;un film plastique si l&apos;on utilise de l&apos;argile expans\u00e9e ;<\/li>\n<\/ul>\n<blockquote><p>\n   Quelle que soit la technique d&apos;imperm\u00e9abilisation, trois couches doivent \u00eatre coul\u00e9es.\n  <\/p><\/blockquote>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_11.jpg\"><\/p>\n<blockquote><p>\n   De mani\u00e8re significative &quot;Penoplex&quot; Le rev\u00eatement de sol, plac\u00e9 sur un coussin de sable, a r\u00e9cemment remplac\u00e9 la couche sup\u00e9rieure de sable (voir photo). Cela augmente le co\u00fbt des travaux mais am\u00e9liore la capacit\u00e9 d&apos;isolation thermique du sol. Si ce n&apos;est pas le cas, il faut proc\u00e9der dans le m\u00eame ordre pour toutes les op\u00e9rations.\n  <\/p><\/blockquote>\n<ul>\n<li>les mat\u00e9riaux d&apos;\u00e9tanch\u00e9it\u00e9 en rouleau sont pos\u00e9s sur du sable s\u00e9ch\u00e9 avec un chevauchement, en chevauchant les murs (de 20 \u00e0 25 cm). Les joints sont coll\u00e9s avec du mastic bitumineux ;<\/li>\n<li>un film de poly\u00e9thyl\u00e8ne est pos\u00e9 sur l&apos;imperm\u00e9abilisation. En outre, avec un chevauchement et une superposition des murs, on pose un treillis d&apos;armature. Les joints du film sont coll\u00e9s \u00e0 l&apos;aide d&apos;un ruban adh\u00e9sif ou d&apos;un fer \u00e0 repasser chaud \u00e0 travers le papier ;<\/li>\n<li>un treillis d&apos;armature est pos\u00e9 ;<\/li>\n<li>la chape est coul\u00e9e.<\/li>\n<\/ul>\n<blockquote><p>\n   \u00c0 titre de comparaison, cette technique est la plus simple et la moins co\u00fbteuse. Il existe d&apos;autres m\u00e9thodes pour \u00e9tanch\u00e9ifier le sol. Cependant, elles sont plus co\u00fbteuses en termes d&apos;intensit\u00e9 de travail et d&apos;argent.\n  <\/p><\/blockquote>\n<h3>Imperm\u00e9abilisation de la sous-couche<\/h3>\n<p>L&apos;imperm\u00e9abilisation et les travaux pr\u00e9paratoires sont les deux principaux moyens de garder le bois d&apos;un plancher sec.<\/p>\n<h4>Travaux pr\u00e9paratoires<\/h4>\n<p>La premi\u00e8re \u00e9tape du processus de pr\u00e9paration consiste \u00e0 nettoyer la surface du sous-plancher de la poussi\u00e8re et des d\u00e9bris. Ensuite, les t\u00e2ches sont ex\u00e9cut\u00e9es dans l&apos;ordre suivant :<\/p>\n<ul>\n<li>un audit des solives, des barres cr\u00e2niennes et des planches est effectu\u00e9, au cours duquel les dommages, les moisissures et les champignons sont identifi\u00e9s ;<\/li>\n<li>le bois endommag\u00e9 par les champignons et les moisissures est enlev\u00e9. Les tentatives d&apos;\u00e9limination des zones endommag\u00e9es \u00e0 l&apos;aide d&apos;un rabot, suivies d&apos;un traitement aux antiseptiques, ne sont pas efficaces dans la plupart des cas. Dans la pratique, les moisissures r\u00e9apparaissent inexplicablement apr\u00e8s quelques ann\u00e9es aux m\u00eames endroits ;<\/li>\n<li>les \u00e9l\u00e9ments de plancher pourris sont remplac\u00e9s ;<\/li>\n<li>les planches d\u00e9tach\u00e9es sont ensuite fix\u00e9es au bloc de b\u00e9ton \u00e0 l&apos;aide de vis autotaraudeuses ;<\/li>\n<li>les n\u0153uds et les fissures tomb\u00e9s sont colmat\u00e9s avec du mastic \u00e0 bois ou un m\u00e9lange de colle PVA et de sciure de bois ;<\/li>\n<li>les d\u00e9chets de construction qui en r\u00e9sultent sont \u00e9limin\u00e9s ;<\/li>\n<li>le bois est impr\u00e9gn\u00e9 d&apos;antiseptiques et d&apos;agents ignifuges (il existe des compositions contenant les deux composants) ;<\/li>\n<li>la base du plancher en planches et les murs d&apos;une hauteur de 20 \u00e0 25 cm sont trait\u00e9s avec un appr\u00eat sp\u00e9cial pour le bois (le processus d&apos;absorption des composants d&apos;imperm\u00e9abilisation liquides, tels que le mastic bitumineux, par le bois est emp\u00each\u00e9). Il est conseill\u00e9 d&apos;acheter un appr\u00eat pr\u00eat \u00e0 l&apos;emploi.<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_13.jpg\"><\/p>\n<p>L&apos;application de l&apos;appr\u00eat se fait au pinceau ou au rouleau. Pour cette raison, les joints entre les murs et le sol sont manipul\u00e9s avec beaucoup de pr\u00e9cautions. Pour. La plupart du temps, en cas d&apos;inondation, c&apos;est l\u00e0 que l&apos;eau se d\u00e9compose. L&apos;appr\u00eat est \u00e9galement appliqu\u00e9 sur le bas des murs jusqu&apos;\u00e0 une hauteur de 10-15 cm. Dans les salles de bains dont les sols en bois doivent \u00eatre imperm\u00e9abilis\u00e9s, les zones humides des murs doivent \u00e9galement \u00eatre appr\u00eat\u00e9es (voir riz).<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_12.jpg\"><\/p>\n<p>Les experts conseillent de traiter \u00e0 nouveau les zones o\u00f9 l&apos;appr\u00eat a \u00e9t\u00e9 rapidement absorb\u00e9 par le bois.<\/p>\n<ul>\n<li>apr\u00e8s le s\u00e9chage de l&apos;appr\u00eat, qui peut durer jusqu&apos;\u00e0 10 heures (vous pouvez le v\u00e9rifier \u00e0 l&apos;aide d&apos;un coton &#8211; il doit rester propre apr\u00e8s contact avec le sol), un ruban autocollant aux propri\u00e9t\u00e9s imperm\u00e9abilisantes est utilis\u00e9 pour coller les joints du sol au mur, les joints entre les planches et les fissures trait\u00e9es au mastic ;<\/li>\n<li>les endroits o\u00f9 passent les lignes \u00e9lectriques sont scell\u00e9s avec du caoutchouc liquide ou des rev\u00eatements en caoutchouc et \u00e9galement scell\u00e9s avec du ruban adh\u00e9sif.<\/li>\n<\/ul>\n<blockquote><p>\n   Remarque : le film autocollant n&apos;est pas utilis\u00e9 pour sceller les joints, les raccords ou les fissures dans l&apos;imperm\u00e9abilisation en rouleau.\n  <\/p><\/blockquote>\n<p>Les travaux pr\u00e9paratoires dans une maison priv\u00e9e, un appartement, un chalet ou un garage sont effectu\u00e9s dans le m\u00eame ordre.<\/p>\n<h3>Imperm\u00e9abilisation avec des mat\u00e9riaux en rouleaux<\/h3>\n<p>Les \u00e9tapes de l&apos;utilisation de mat\u00e9riaux roul\u00e9s pour imperm\u00e9abiliser un sol en bois sont les suivantes :<\/p>\n<ul>\n<li>le mat\u00e9riau d\u00e9roul\u00e9 est d\u00e9coup\u00e9 en bandes d&apos;une longueur \u00e9gale \u00e0 la taille de la pi\u00e8ce dans laquelle les travaux d&apos;imperm\u00e9abilisation seront effectu\u00e9s, plus une approche des murs de 10 \u00e0 15 cm de chaque c\u00f4t\u00e9. Lors du calcul du nombre de bandes, il est n\u00e9cessaire de tenir compte de la pose par chevauchement ;<\/li>\n<li>les feuilles d\u00e9coup\u00e9es sont d\u00e9roul\u00e9es (elles peuvent \u00eatre superpos\u00e9es dans le couloir) et laiss\u00e9es dans cet \u00e9tat pendant la nuit (les tensions qui se sont produites \u00e0 la surface du mat\u00e9riau pendant qu&apos;il \u00e9tait dans le rouleau sont \u00e9limin\u00e9es) ;<\/li>\n<li>le mastic d&apos;\u00e9tanch\u00e9it\u00e9 est appliqu\u00e9 sur le sol et le bas des murs \u00e0 l&apos;aide d&apos;un rouleau ou d&apos;une natte &#8211; il sert d&apos;adh\u00e9sif pour l&apos;isolation en rouleau si une composition adh\u00e9sive n&apos;est pas appliqu\u00e9e sur celui-ci \u00e0 l&apos;usine ;<\/li>\n<li>apr\u00e8s 5-6 heures, une deuxi\u00e8me couche de mastic est appliqu\u00e9e, perpendiculairement aux coups de la premi\u00e8re couche ;<\/li>\n<li>\u00e0 l&apos;aide d&apos;un m\u00e8tre ruban, rep\u00e9rez le milieu de la bande roul\u00e9e, o\u00f9 vous ferez une marque avec un marqueur ;<\/li>\n<li>les toiles sont torsad\u00e9es aux deux extr\u00e9mit\u00e9s, de mani\u00e8re \u00e0 ce que les deux rouleaux se rejoignent exactement au milieu ;<\/li>\n<li>trouver le milieu de la pi\u00e8ce (la marque sur le rouleau doit \u00eatre exactement au milieu de la pi\u00e8ce) ;<\/li>\n<li>tout d&apos;abord, une partie de la bande est d\u00e9roul\u00e9e (un rouleau) ;<\/li>\n<li>Pour s&apos;assurer que le mat\u00e9riau d&apos;imperm\u00e9abilisation adh\u00e8re bien aux planches, il est roul\u00e9 avec un rouleau \u00e0 tapisser ou repass\u00e9 avec force avec les mains. Si cette op\u00e9ration n&apos;est pas effectu\u00e9e \u00e0 temps, des poches d&apos;air peuvent se former, qui devront \u00eatre perc\u00e9es (les experts ne voient toutefois pas de probl\u00e8mes dans les perforations, estimant qu&apos;elles gu\u00e9rissent avec le temps) ;<\/li>\n<li>d\u00e9rouler la deuxi\u00e8me partie du rouleau ;<\/li>\n<li>poser la deuxi\u00e8me feuille de la m\u00eame mani\u00e8re, mais en faisant chevaucher la premi\u00e8re de 10 \u00e0 15 cm seulement. Les joints sont coll\u00e9s avec du mastic ;<\/li>\n<li>apr\u00e8s avoir pos\u00e9 le mat\u00e9riau d&apos;\u00e9tanch\u00e9it\u00e9 dans toute la pi\u00e8ce, coller les joints lat\u00e9raux du sol avec le mur. Pour ce faire, d\u00e9coupez une bande de mat\u00e9riau d&apos;\u00e9tanch\u00e9it\u00e9 de 30 \u00e0 40 cm de large et collez-la au sol (environ 10 cm) et au mur (le reste) \u00e0 l&apos;aide de mastic (les sp\u00e9cialistes exp\u00e9riment\u00e9s commencent imm\u00e9diatement le rouleau sur le mur lat\u00e9ral, ce qui est plus fiable, mais tr\u00e8s difficile et peu pratique \u00e0 r\u00e9aliser).<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_14.jpg\"><\/p>\n<blockquote><p>\n   Sachez que l&apos;imperm\u00e9abilisation en rouleau fonctionne mieux dans les cuisines, les salles de bains, les balcons et les douches.\n  <\/p><\/blockquote>\n<h3>Imperm\u00e9abilisation avec des peintures<\/h3>\n<p>Les peintures imperm\u00e9ables \u00e0 base de polym\u00e8res et de bitume sont le type d&apos;imperm\u00e9abilisation le moins co\u00fbteux. Mais leur dur\u00e9e de vie ne d\u00e9passe pas sept ans. appliqu\u00e9 en deux ou trois couches \u00e0 l&apos;aide de pinceaux ordinaires sur des planches ponc\u00e9es et s\u00e9ch\u00e9es. Chaque nouvelle couche est pos\u00e9e sur la couche enti\u00e8rement s\u00e8che avant d&apos;\u00eatre appliqu\u00e9e en deux ou trois couches \u00e0 l&apos;aide de pinceaux ordinaires sur des planches ponc\u00e9es et s\u00e9ch\u00e9es. Les applications id\u00e9ales sont les finitions des sols de cuisine ou sous le linol\u00e9um.<\/p>\n<h3>Imperm\u00e9abilisation avec des mat\u00e9riaux de rev\u00eatement<\/h3>\n<p>Pr\u00e9parez une solution de rev\u00eatement avant de commencer. Pour ce faire, pr\u00e9parez une cr\u00e8me acidul\u00e9e \u00e0 teneur moyenne en mati\u00e8re grasse en diluant le m\u00e9lange sec dans un r\u00e9cipient \u00e0 raison de 1:1 avec de l&apos;eau et en remuant bien. Le sol et le bas des murs sont trait\u00e9s avec la composition obtenue (10-15 cm au-dessus du niveau du sol). Pour les surfaces planes, utiliser un rouleau ; pour les espaces restreints, utiliser un pinceau. Il s&apos;agit d&apos;appliquer l&apos;isolant en deux couches. Apr\u00e8s quatre \u00e0 six heures, la deuxi\u00e8me couche est appliqu\u00e9e perpendiculairement \u00e0 la premi\u00e8re. Le sol est ensuite laiss\u00e9 \u00e0 s\u00e9cher pendant une journ\u00e9e enti\u00e8re.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_15.jpg\"><\/p>\n<h3>Imperm\u00e9abilisation avec des mastics<\/h3>\n<p>Le mode d&apos;emploi des mastics pour imperm\u00e9abiliser un plancher en bois est simple :<\/p>\n<ul>\n<li>\u00e0 l&apos;aide d&apos;un pinceau, le mastic est appliqu\u00e9 sur les joints du sol et des murs, ainsi qu&apos;aux endroits o\u00f9 passent les lignes \u00e9lectriques ;<\/li>\n<li>une bande d&apos;\u00e9tanch\u00e9it\u00e9 sp\u00e9ciale est coll\u00e9e sur l&apos;isolation appliqu\u00e9e (au niveau des joints entre les murs et le sol). Lors de la pose, il est n\u00e9cessaire d&apos;\u00e9liminer les plis et les poches d&apos;air ;<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_16.jpg\"><\/p>\n<ul>\n<li>une autre couche d&apos;isolation est appliqu\u00e9e sur la bande coll\u00e9e ;<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_17.jpg\"><\/p>\n<ul>\n<li>les m\u00eames actions sont effectu\u00e9es dans les endroits o\u00f9 passent les communications ;<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter\"  src=\"\/wp-content\/uploads\/2024\/07\/gidroizoljacija-pola-v-derevjannom-dome_18.jpg\"><\/p>\n<ul>\n<li>Le mastic est appliqu\u00e9 au rouleau sur une surface plane.<\/li>\n<\/ul>\n<p>Les experts conseillent de traiter le sol en deux couches.<\/p>\n<h3>Imperm\u00e9abilisation par impr\u00e9gnation<\/h3>\n<p>Les meilleures m\u00e9thodes pour imperm\u00e9abiliser les sols en bois dans les salles de bains, les buanderies, les hammams, les douches et les saunas \u00e0 vapeur sont les impr\u00e9gnations. Ici, c&apos;est l&apos;humidit\u00e9, et non les fuites d&apos;eau, qui prot\u00e8ge le bois lui-m\u00eame. La m\u00e9thode d&apos;imperm\u00e9abilisation est donc diff\u00e9rente : le bois (planches, solives et barres) pr\u00e9par\u00e9 pour l&apos;installation du plancher est immerg\u00e9 dans un bain unique contenant une composition d&apos;impr\u00e9gnation pendant une journ\u00e9e enti\u00e8re. Avec toute autre m\u00e9thode d&apos;impr\u00e9gnation, la face inf\u00e9rieure du sol reste expos\u00e9e et se d\u00e9grade rapidement.<\/p>\n<p>Si vous voulez garder votre maison en bois intacte et durable, vous devez imperm\u00e9abiliser vos sols. Vous pouvez \u00e9viter les probl\u00e8mes structurels, la formation de moisissures et les d\u00e9g\u00e2ts des eaux sur vos planchers en prenant le temps de les sceller et de les prot\u00e9ger correctement. Vous contribuerez ainsi \u00e0 la s\u00e9curit\u00e9 et au confort de votre espace de vie, tout en augmentant la valeur de votre maison.<\/p>\n<p>Il est essentiel de choisir les outils et les m\u00e9thodes appropri\u00e9s \u00e0 vos besoins particuliers. La cr\u00e9ation d&apos;une barri\u00e8re \u00e9tanche efficace n\u00e9cessite l&apos;utilisation de mastics, de membranes et de techniques d&apos;installation appropri\u00e9es, entre autres. Veillez \u00e0 toujours suivre les instructions du fabricant et, si vous avez des questions concernant une \u00e9tape du processus, pensez \u00e0 consulter un professionnel.<\/p>\n<p>L&apos;imperm\u00e9abilisation initiale n&apos;est pas aussi importante que l&apos;entretien et les inspections de routine. Si vous remarquez une usure ou un dommage, gardez l&apos;\u0153il ouvert et agissez rapidement pour \u00e9viter que les petits probl\u00e8mes ne s&apos;aggravent. Avec un peu de travail et d&apos;attention aux d\u00e9tails, vous pourrez profiter pendant des ann\u00e9es d&apos;un sol sec et solide dans votre maison en bois.<\/p>\n<h2>Vid\u00e9o sur le sujet<\/h2>\n<h3>Imperm\u00e9abilisation d&apos;un sol en terre<\/h3>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/WdgsvHIsoqo\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<h3>Imperm\u00e9abilisation des panneaux OSB. Flachendicht from knauf.<\/h3>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/abI_31YUOYE\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<h3>Imperm\u00e9abilisation des sols. Classe de ma\u00eetre \/\/ FORUMHOUSE<\/h3>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/lPavCj5A0r0\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour qu&apos;une maison en bois reste confortable et structurellement saine, le sol doit \u00eatre imperm\u00e9abilis\u00e9. Les planchers en bois sont particuli\u00e8rement sensibles aux probl\u00e8mes li\u00e9s \u00e0 l&apos;humidit\u00e9, tels que la pourriture, la moisissure et le gauchissement. Vous pouvez prot\u00e9ger votre maison et augmenter la dur\u00e9e de vie de vos planchers en bois en veillant \u00e0 [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-9310","post","type-post","status-publish","format-standard","","category-house"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imperm\u00e9abilisation d&amp;apos;un plancher en bois dans une maison priv\u00e9e, \u00e0 r\u00e9aliser soi-m\u00eame<\/title>\n<meta name=\"description\" content=\"Apprenez des m\u00e9thodes efficaces pour imperm\u00e9abiliser un plancher dans une maison en bois afin de pr\u00e9venir les dommages caus\u00e9s par l&amp;apos;humidit\u00e9 et de garantir une structure durable. Guide \u00e9tape par \u00e9tape inclus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imperm\u00e9abilisation d&amp;apos;un plancher en bois dans une maison priv\u00e9e, \u00e0 r\u00e9aliser soi-m\u00eame\" \/>\n<meta property=\"og:description\" content=\"Apprenez des m\u00e9thodes efficaces pour imperm\u00e9abiliser un plancher dans une maison en bois afin de pr\u00e9venir les dommages caus\u00e9s par l&amp;apos;humidit\u00e9 et de garantir une structure durable. Guide \u00e9tape par \u00e9tape inclus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/\" \/>\n<meta property=\"og:site_name\" content=\"StroyArsenal62.com\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T07:29:11+00:00\" \/>\n<meta name=\"author\" content=\"Milan Yashina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Milan Yashina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"36 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/\"},\"author\":{\"name\":\"Milan Yashina\",\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/#\\\/schema\\\/person\\\/b0bdc489f578ed260812eeef5fd1c94b\"},\"headline\":\"Imperm\u00e9abilisation d&rsquo;un plancher dans une maison en bois\",\"datePublished\":\"2024-07-22T07:29:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/\"},\"wordCount\":7130,\"commentCount\":0,\"articleSection\":[\"La maison\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/\",\"url\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/\",\"name\":\"Imperm\u00e9abilisation d&apos;un plancher en bois dans une maison priv\u00e9e, \u00e0 r\u00e9aliser soi-m\u00eame\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-07-22T07:29:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/#\\\/schema\\\/person\\\/b0bdc489f578ed260812eeef5fd1c94b\"},\"description\":\"Apprenez des m\u00e9thodes efficaces pour imperm\u00e9abiliser un plancher dans une maison en bois afin de pr\u00e9venir les dommages caus\u00e9s par l&apos;humidit\u00e9 et de garantir une structure durable. Guide \u00e9tape par \u00e9tape inclus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/waterproofing-a-floor-in-a-wooden-house\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Maison\",\"item\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imperm\u00e9abilisation d&#8217;un plancher dans une maison en bois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/\",\"name\":\"StroyArsenal62.com\",\"description\":\"Tout sur la construction et la r\u00e9novation de A \u00e0 Z\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/#\\\/schema\\\/person\\\/b0bdc489f578ed260812eeef5fd1c94b\",\"name\":\"Milan Yashina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/904e61e675cac60401ca6d98266c5b61c27cc2e3e4dddc6bace7cf726d0a439e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/904e61e675cac60401ca6d98266c5b61c27cc2e3e4dddc6bace7cf726d0a439e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/904e61e675cac60401ca6d98266c5b61c27cc2e3e4dddc6bace7cf726d0a439e?s=96&d=mm&r=g\",\"caption\":\"Milan Yashina\"},\"description\":\"Ing\u00e9nieur concepteur, sp\u00e9cialiste de l'\u00e9laboration de documents de conception. Je vous aiderai \u00e0 concevoir correctement votre maison ou autre b\u00e2timent.\",\"url\":\"https:\\\/\\\/stroyarsenal62.com\\\/fr\\\/author\\\/author-publications-fr_2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imperm\u00e9abilisation d&apos;un plancher en bois dans une maison priv\u00e9e, \u00e0 r\u00e9aliser soi-m\u00eame","description":"Apprenez des m\u00e9thodes efficaces pour imperm\u00e9abiliser un plancher dans une maison en bois afin de pr\u00e9venir les dommages caus\u00e9s par l&apos;humidit\u00e9 et de garantir une structure durable. Guide \u00e9tape par \u00e9tape inclus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/","og_locale":"fr_FR","og_type":"article","og_title":"Imperm\u00e9abilisation d&apos;un plancher en bois dans une maison priv\u00e9e, \u00e0 r\u00e9aliser soi-m\u00eame","og_description":"Apprenez des m\u00e9thodes efficaces pour imperm\u00e9abiliser un plancher dans une maison en bois afin de pr\u00e9venir les dommages caus\u00e9s par l&apos;humidit\u00e9 et de garantir une structure durable. Guide \u00e9tape par \u00e9tape inclus.","og_url":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/","og_site_name":"StroyArsenal62.com","article_published_time":"2024-07-22T07:29:11+00:00","author":"Milan Yashina","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Milan Yashina","Dur\u00e9e de lecture estim\u00e9e":"36 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/#article","isPartOf":{"@id":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/"},"author":{"name":"Milan Yashina","@id":"https:\/\/stroyarsenal62.com\/fr\/#\/schema\/person\/b0bdc489f578ed260812eeef5fd1c94b"},"headline":"Imperm\u00e9abilisation d&rsquo;un plancher dans une maison en bois","datePublished":"2024-07-22T07:29:11+00:00","mainEntityOfPage":{"@id":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/"},"wordCount":7130,"commentCount":0,"articleSection":["La maison"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/","url":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/","name":"Imperm\u00e9abilisation d&apos;un plancher en bois dans une maison priv\u00e9e, \u00e0 r\u00e9aliser soi-m\u00eame","isPartOf":{"@id":"https:\/\/stroyarsenal62.com\/fr\/#website"},"datePublished":"2024-07-22T07:29:11+00:00","author":{"@id":"https:\/\/stroyarsenal62.com\/fr\/#\/schema\/person\/b0bdc489f578ed260812eeef5fd1c94b"},"description":"Apprenez des m\u00e9thodes efficaces pour imperm\u00e9abiliser un plancher dans une maison en bois afin de pr\u00e9venir les dommages caus\u00e9s par l&apos;humidit\u00e9 et de garantir une structure durable. Guide \u00e9tape par \u00e9tape inclus.","breadcrumb":{"@id":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stroyarsenal62.com\/fr\/waterproofing-a-floor-in-a-wooden-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Maison","item":"https:\/\/stroyarsenal62.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Imperm\u00e9abilisation d&#8217;un plancher dans une maison en bois"}]},{"@type":"WebSite","@id":"https:\/\/stroyarsenal62.com\/fr\/#website","url":"https:\/\/stroyarsenal62.com\/fr\/","name":"StroyArsenal62.com","description":"Tout sur la construction et la r\u00e9novation de A \u00e0 Z","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stroyarsenal62.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/stroyarsenal62.com\/fr\/#\/schema\/person\/b0bdc489f578ed260812eeef5fd1c94b","name":"Milan Yashina","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/904e61e675cac60401ca6d98266c5b61c27cc2e3e4dddc6bace7cf726d0a439e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/904e61e675cac60401ca6d98266c5b61c27cc2e3e4dddc6bace7cf726d0a439e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/904e61e675cac60401ca6d98266c5b61c27cc2e3e4dddc6bace7cf726d0a439e?s=96&d=mm&r=g","caption":"Milan Yashina"},"description":"Ing\u00e9nieur concepteur, sp\u00e9cialiste de l'\u00e9laboration de documents de conception. Je vous aiderai \u00e0 concevoir correctement votre maison ou autre b\u00e2timent.","url":"https:\/\/stroyarsenal62.com\/fr\/author\/author-publications-fr_2\/"}]}},"_links":{"self":[{"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/posts\/9310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/comments?post=9310"}],"version-history":[{"count":0,"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/posts\/9310\/revisions"}],"wp:attachment":[{"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/media?parent=9310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/categories?post=9310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stroyarsenal62.com\/fr\/wp-json\/wp\/v2\/tags?post=9310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}